{"id":12864,"date":"2021-06-25T10:30:44","date_gmt":"2021-06-25T14:30:44","guid":{"rendered":"https:\/\/www.caissealliance.com\/?p=12864"},"modified":"2021-06-25T10:20:40","modified_gmt":"2021-06-25T14:20:40","slug":"10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur","status":"publish","type":"post","link":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/","title":{"rendered":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>NORTH BAY \u2013 Le 21 juin 2021\u00a0:<\/strong> Pour une deuxi\u00e8me ann\u00e9e cons\u00e9cutive, la Caisse Alliance annonce qu\u2019elle a attribu\u00e9 10\u00a0000 $ en bourses d\u2019\u00e9tudes, soit une Bourse Caisse Alliance de 5\u00a0000 $ \u00e0 une \u00e9tudiante qui termine ses \u00e9tudes secondaires et qui est inscrite \u00e0 un programme postsecondaire, ainsi qu\u2019une seconde Bourse Caisse Alliance de 5\u00a0000 $ \u00e0 un \u00e9tudiant d\u00e9j\u00e0 inscrit \u00e0 un programme coll\u00e9gial ou universitaire de premier cycle.<\/p>\n<p style=\"text-align: justify;\">Les \u00e9tudiants membres de notre coop\u00e9rative financi\u00e8re avaient jusqu\u2019au 31 mars 2021 pour soumettre une demande.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0La participation de la communaut\u00e9 \u00e9tudiante a surpass\u00e9 de 23 % celle de l\u2019an dernier et a donn\u00e9 lieu, au sein du comit\u00e9 de s\u00e9lection des boursiers, \u00e0 des \u00e9valuations approfondies et \u00e0 des \u00e9changes int\u00e9ressants, indique M. Philippe Boissonneault, pr\u00e9sident du conseil d\u2019administration de la Caisse Alliance. Form\u00e9 de membres de la communaut\u00e9, le comit\u00e9 de s\u00e9lection avait comme mandat de s\u00e9lectionner, en conformit\u00e9 avec les crit\u00e8res d\u2019admissibilit\u00e9 \u00e9tablis, deux candidats s\u2019\u00e9tant distingu\u00e9s en participant ou en amor\u00e7ant un projet visant \u00e0 soutenir les membres de leur communaut\u00e9 en cette p\u00e9riode de crise pand\u00e9mique.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Selon M. Pierre Dorval, pr\u00e9sident et chef de la direction de la Caisse Alliance, les initiatives entreprises par les candidats sont nombreuses et porteuses de solutions. \u00ab\u00a0Pour la Caisse Alliance, la sant\u00e9 et le bien-\u00eatre de \u2018nos jeunes b\u00e2tisseurs de bonheur\u2019 sont de grande importance. Avec le surcro\u00eet de stress, d\u2019angoisse et d\u2019anxi\u00e9t\u00e9 que l\u2019on observe entre autres chez nos jeunes depuis la derni\u00e8re ann\u00e9e, les projets pr\u00e9sent\u00e9s auront sans aucun doute des r\u00e9percussions positives imm\u00e9diates et\/ou \u00e0 long terme.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Les deux heureux r\u00e9cipiendaires ont, chacun \u00e0 leur tour, eu droit \u00e0 une annonce surprise, les 15 et 17 juin dernier, lors d\u2019un entretien par vid\u00e9oconf\u00e9rence en pr\u00e9sence de gestionnaires de la Caisse Alliance et de membres du comit\u00e9 de s\u00e9lection.<\/p>\n<p><strong>R\u00e9cipiendaire du secondaire inscrite \u00e0 un programme postsecondaire<\/strong><\/p>\n<p style=\"text-align: justify;\">Domicili\u00e9e \u00e0 Cache Bay, dans la r\u00e9gion du Nipissing, Aysha Nuh, nouvelle dipl\u00f4m\u00e9e de l\u2019\u00c9cole secondaire catholique Franco-Cit\u00e9 et inscrite au programme de g\u00e9nie chimique \u00e0 l\u2019Universit\u00e9 Western, fait partie des choix du comit\u00e9. Soulignons l\u2019impact significatif et continu de son projet collaboratif intitul\u00e9 <em>Le d\u00e9fi de la sant\u00e9 mentale chez les jeunes<\/em>, une initiative de sensibilisation et d\u2019\u00e9ducation, de m\u00eame qu\u2019une source d\u2019aide directe \u00e0 la jeunesse en cette p\u00e9riode de crise sanitaire.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Les gens doivent s\u2019isoler pour arr\u00eater la propagation de la COVID-19, ce qui se r\u00e9sulte en une diminution de socialisation et d\u2019interactions humaines, mentionne la boursi\u00e8re. Ce projet permet aux adolescents d\u2019avoir une voix, de se ressentir \u00e9cout\u00e9s et de savoir qu\u2019ils ne sont pas seuls.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Ce projet \u00e0 valeur coop\u00e9rative a particuli\u00e8rement retenu l\u2019attention du comit\u00e9 de s\u00e9lection, notamment en raison de ses objectifs fondamentaux et de son influence compte tenu du contexte pand\u00e9mique actuel.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0\u00c7a me fait toujours plaisir de voir des adolescents qui s\u2019impliquent aupr\u00e8s de leurs pairs pour les aider \u00e0 passer au travers de p\u00e9riodes difficiles, souligne M. Boissonneault. On r\u00e9alise que la pand\u00e9mie a eu des effets tr\u00e8s n\u00e9fastes et difficiles sur eux.\u00a0\u00bb<\/p>\n<p><strong>R\u00e9cipiendaire d\u00e9j\u00e0 inscrit \u00e0 un programme coll\u00e9gial ou universitaire de premier cycle<\/strong><\/p>\n<p style=\"text-align: justify;\">Nouveau d\u00e9tenteur d\u2019un baccalaur\u00e9at en psychologie de l\u2019Universit\u00e9 de Hearst et inscrit \u00e0 la formation \u00e0 l\u2019enseignement \u00e0 l\u2019Universit\u00e9 d\u2019Ottawa, Bradley Morin a men\u00e9 un projet de recherche qualitatif d\u2019envergure ayant pour but de favoriser la r\u00e9tention des enseignants dans le contexte actuel. De Kapuskasing, dans la r\u00e9gion du Nord, ce dernier a su pr\u00e9senter un projet faisant preuve de r\u00e9flexion, aidant \u00e0 tenir compte et \u00e0 mieux comprendre les besoins et r\u00e9alit\u00e9s du personnel enseignant francophone de la r\u00e9gion, et ayant le potentiel de contribuer de mani\u00e8re significative \u00e0 leur bien-\u00eatre.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0L\u2019\u00e9cole virtuelle, ce n\u2019est pas toujours l\u2019id\u00e9al pour les enseignants, ni pour les \u00e9l\u00e8ves. \u00catre capable d\u2019avoir le soutien de tout le monde \u2013 de la direction et de ses autres coll\u00e8gues de travail \u2013 pour travailler ensemble, c\u2019est important. J\u2019ai vu beaucoup, dans le cadre de mon projet, que le niveau de stress des enseignants a augment\u00e9 significativement dans le contexte de pand\u00e9mie, donc le but est de trouver des fa\u00e7ons de diminuer ce stress.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Comme Aysha Nuh, le boursier affirme vouloir continuer \u00e0 contribuer \u00e0 l\u2019\u00e9volution de son projet.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0De nombreux facteurs influent sur la r\u00e9alit\u00e9 dans laquelle \u00e9volue l\u2019\u00e9ducation \u00e0 l\u2019heure actuelle, poursuit M. Boissonneault. Cette situation sans pr\u00e9c\u00e9dent comporte son lot de d\u00e9fis pour les enseignants qui doivent composer avec la courbe d\u2019apprentissage de la technologie n\u00e9cessaire pour l\u2019\u00e9ducation \u00e0 distance ainsi que la r\u00e9organisation, l\u2019adaptation et le travail d\u2019\u00e9quipe continus afin que la client\u00e8le \u00e9tudiante puisse continuer \u00e0 s\u2019instruire durant cette p\u00e9riode d\u2019incertitude.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Le comit\u00e9 de s\u00e9lection boursier tient \u00e0 remercier tous les candidats et \u00e0 f\u00e9liciter chacun d\u2019entre eux pour leurs r\u00e9alisations et actes de solidarit\u00e9 remarquables.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u2013 30 \u2013<\/p>\n<p>&nbsp;<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/HfOAJq7YrMw\" width=\"960\" height=\"540\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n<p><strong>Contact m\u00e9diatique :<br \/>\n<\/strong>Manon Aubin<br \/>\nConseill\u00e8re en communication interne et m\u00e9dias sociaux<br \/>\nT\u00e9l.\u00a0: 705\u00a0474-5634, poste 7271<br \/>\nCourriel\u00a0: manon.aubin@acpol.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NORTH BAY \u2013 Le 21 juin 2021\u00a0: Pour une deuxi\u00e8me ann\u00e9e cons\u00e9cutive, la Caisse Alliance annonce qu\u2019elle a attribu\u00e9 10\u00a0000 $ en bourses d\u2019\u00e9tudes, soit une Bourse Caisse Alliance de 5\u00a0000 $ \u00e0 une \u00e9tudiante qui termine ses \u00e9tudes secondaires et qui est inscrite \u00e0 un programme postsecondaire, ainsi qu\u2019une seconde Bourse Caisse Alliance de [&#8230;]<\/p>\n","protected":false},"author":7,"featured_media":7247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,56],"tags":[],"class_list":["post-12864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulier","category-jeunesse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance\" \/>\n<meta property=\"og:description\" content=\"NORTH BAY \u2013 Le 21 juin 2021\u00a0: Pour une deuxi\u00e8me ann\u00e9e cons\u00e9cutive, la Caisse Alliance annonce qu\u2019elle a attribu\u00e9 10\u00a0000 $ en bourses d\u2019\u00e9tudes, soit une Bourse Caisse Alliance de 5\u00a0000 $ \u00e0 une \u00e9tudiante qui termine ses \u00e9tudes secondaires et qui est inscrite \u00e0 un programme postsecondaire, ainsi qu\u2019une seconde Bourse Caisse Alliance de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/\" \/>\n<meta property=\"og:site_name\" content=\"Caisse Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-25T14:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9mi Dumais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9mi Dumais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/\"},\"author\":{\"name\":\"R\u00e9mi Dumais\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/#\\\/schema\\\/person\\\/c840989c09fa0e4a30bc7807cac9b847\"},\"headline\":\"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur\",\"datePublished\":\"2021-06-25T14:30:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/\"},\"wordCount\":913,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caissealliance.com\\\/wp-content\\\/uploads\\\/cap-celebrate-celebration-1205651.jpg\",\"articleSection\":[\"Particuliers\",\"Jeunesse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/\",\"url\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/\",\"name\":\"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caissealliance.com\\\/wp-content\\\/uploads\\\/cap-celebrate-celebration-1205651.jpg\",\"datePublished\":\"2021-06-25T14:30:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/#\\\/schema\\\/person\\\/c840989c09fa0e4a30bc7807cac9b847\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.caissealliance.com\\\/wp-content\\\/uploads\\\/cap-celebrate-celebration-1205651.jpg\",\"contentUrl\":\"https:\\\/\\\/www.caissealliance.com\\\/wp-content\\\/uploads\\\/cap-celebrate-celebration-1205651.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/particulier\\\/jeunesse\\\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/\",\"name\":\"Caisse Alliance\",\"description\":\"Site Web de la Caisse Alliance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.caissealliance.com\\\/fr\\\/#\\\/schema\\\/person\\\/c840989c09fa0e4a30bc7807cac9b847\",\"name\":\"R\u00e9mi Dumais\",\"sameAs\":[\"http:\\\/\\\/www.caissealliance.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/","og_locale":"fr_FR","og_type":"article","og_title":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance","og_description":"NORTH BAY \u2013 Le 21 juin 2021\u00a0: Pour une deuxi\u00e8me ann\u00e9e cons\u00e9cutive, la Caisse Alliance annonce qu\u2019elle a attribu\u00e9 10\u00a0000 $ en bourses d\u2019\u00e9tudes, soit une Bourse Caisse Alliance de 5\u00a0000 $ \u00e0 une \u00e9tudiante qui termine ses \u00e9tudes secondaires et qui est inscrite \u00e0 un programme postsecondaire, ainsi qu\u2019une seconde Bourse Caisse Alliance de [...]","og_url":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/","og_site_name":"Caisse Alliance","article_published_time":"2021-06-25T14:30:44+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg","type":"image\/jpeg"}],"author":"R\u00e9mi Dumais","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00e9mi Dumais","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#article","isPartOf":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/"},"author":{"name":"R\u00e9mi Dumais","@id":"https:\/\/www.caissealliance.com\/fr\/#\/schema\/person\/c840989c09fa0e4a30bc7807cac9b847"},"headline":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur","datePublished":"2021-06-25T14:30:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/"},"wordCount":913,"commentCount":0,"image":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg","articleSection":["Particuliers","Jeunesse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/","url":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/","name":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur | Caisse Alliance","isPartOf":{"@id":"https:\/\/www.caissealliance.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#primaryimage"},"image":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg","datePublished":"2021-06-25T14:30:44+00:00","author":{"@id":"https:\/\/www.caissealliance.com\/fr\/#\/schema\/person\/c840989c09fa0e4a30bc7807cac9b847"},"breadcrumb":{"@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#primaryimage","url":"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg","contentUrl":"https:\/\/www.caissealliance.com\/wp-content\/uploads\/cap-celebrate-celebration-1205651.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.caissealliance.com\/fr\/particulier\/jeunesse\/10-000-en-bourses-decernees-a-deux-jeunes-batisseurs-de-bonheur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caissealliance.com\/fr\/"},{"@type":"ListItem","position":2,"name":"10 000 $ en bourses d\u00e9cern\u00e9es \u00e0 deux jeunes b\u00e2tisseurs de bonheur"}]},{"@type":"WebSite","@id":"https:\/\/www.caissealliance.com\/fr\/#website","url":"https:\/\/www.caissealliance.com\/fr\/","name":"Caisse Alliance","description":"Site Web de la Caisse Alliance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caissealliance.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.caissealliance.com\/fr\/#\/schema\/person\/c840989c09fa0e4a30bc7807cac9b847","name":"R\u00e9mi Dumais","sameAs":["http:\/\/www.caissealliance.com"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:56:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/posts\/12864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/comments?post=12864"}],"version-history":[{"count":5,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/posts\/12864\/revisions"}],"predecessor-version":[{"id":12889,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/posts\/12864\/revisions\/12889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/media\/7247"}],"wp:attachment":[{"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/media?parent=12864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/categories?post=12864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caissealliance.com\/fr\/wp-json\/wp\/v2\/tags?post=12864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}